{"id":5685,"date":"2013-12-18T11:28:07","date_gmt":"2013-12-18T11:28:07","guid":{"rendered":"http:\/\/www.evasanagustin.com\/workaholic\/?p=5685"},"modified":"2013-12-22T21:24:08","modified_gmt":"2013-12-22T21:24:08","slug":"media-news-s51-a13","status":"publish","type":"post","link":"https:\/\/www.evasanagustin.com\/workaholic\/2013\/12\/18\/media-news-s51-a13\/","title":{"rendered":"Media News S51 A13"},"content":{"rendered":"<p><strong>Publicidad<\/strong><br \/>\nNo es la primera vez que hablo de publicidad extranjera aprovechando que he estado unos d\u00edas de vacaciones. Siempre me resulta curioso ver las similitudes y diferencias, tanto en conceptos como en marcas. As\u00ed que cuando vi uno que me pareci\u00f3 igualito <a href=\"http:\/\/www.youtube.com\/watch?v=-8R97z7XXQ0\">al de Ikea<\/a> pens\u00e9 que hab\u00edan adaptado el perfil m\u00e1s n\u00f3rdico a los personajes porque la historia que contaba era la misma: una mujer entrando en casa y siguiendo un caminito de velas hasta encontrar a su marido prepar\u00e1ndole un ba\u00f1o relajante. Lo curioso es que no soy capaz de recordar qui\u00e9n era el anunciante pero, eso s\u00ed, no ten\u00eda nada que ver con muebles ni decoraci\u00f3n ni nada relacionado con Ikea. Un ejemplo m\u00e1s de que los anuncios se inspiran en ellos mismos.<\/p>\n<p><strong>Cine<\/strong><br \/>\nElegir la butaca del cine puede ser tan complicado como elegir mesa en un restaurante: depende de la distribuci\u00f3n de la sala (peque\u00f1a, en grada, con pasillos&#8230;), de cu\u00e1nta gente vaya a sentarse (uno, dos, un grupo), de los que vayamos a tener al lado (gente que ocupa m\u00e1s espacio del que deber\u00eda o restaurantes que juntan las mesas demasiado), de lo que se vaya a ver\/comer (no es lo mismo un pintxo que un men\u00fa degustaci\u00f3n, tampoco una peli de acci\u00f3n que un drama en VOS), del cu\u00e1ndo se reserva la entrada&#8230; en fin, muchas cosas.\u00a0 Tantas que alguien ha hecho <a href=\"http:\/\/www.blogdecine.com\/otros\/tu-butaca-define-tu-personalidad\">un estudio psicol\u00f3gico<\/a> para definir la personalidad en funci\u00f3n de d\u00f3nde nos sentamos en el cine. \u00bfCu\u00e1l ser\u00e1 para los que \u00faltimamente solo lo vemos desde el sof\u00e1?<\/p>\n<p><strong>Internet<\/strong><br \/>\n\u00bfQue m\u00e1s de la mitad del tr\u00e1fico online es de bots y maquinitas? \u00bfM\u00e1s tr\u00e1fico no humano que personas navegando? Vaya cosa pero <a href=\"http:\/\/www.theatlantic.com\/technology\/archive\/2013\/12\/welcome-to-the-internet-of-thingies-615-of-web-traffic-is-not-human\/282309\/\">eso parece<\/a>. Conviene reflexionar, sobre todo a los que creemos que los contenidos han de estar pensados para la parte humana de nuestras visitas. Quiz\u00e1 sea el momento de plantearse cu\u00e1ntos de esos crawlers necesitamos para encontrar algo en la mara\u00f1a de la www. \u00bfEs m\u00e1s libertad o m\u00e1s derroche? Sea como sea parece que va en aumento as\u00ed que para algunos ser\u00e1 la excusa perfecta para justificar el enfocar los contenidos m\u00e1s a la parte t\u00e9cnica que a la personal. Espero que tambi\u00e9n lo sea para que las m\u00e1quinas comprendan mejor a los humanos.<\/p>\n<p><strong>Televisi\u00f3n<\/strong><br \/>\nLa tele ya no es lo que era, ni por canales ni por programas ni por los personajes que aparecen en ella. Hay mucha basura, tanta que a duras penas se digieren algunas franjas horarias. Otras, en cambio, rebosan de series que obligan a m\u00e1s de uno a ver, grabar y esperar la repetici\u00f3n para no perderse su cap\u00edtulo favorito. La mezcla es ciertamente extra\u00f1a y parece hasta normal que aparezcan <a href=\"http:\/\/www.vertele.com\/noticias\/llegan-a-espana-los-primeros-premios-a-lo-peor-de-nuestra-television\/\">premios a lo peor que se emite en Espa\u00f1a<\/a>, hay d\u00edas que nominar\u00eda a unos cuantos. Aunque lo que demuestra que ha cambiado (y mucho) es <a href=\"http:\/\/www.abc.es\/tv\/20131216\/abci-publico-television-201312132225.html\">tener que pagar<\/a> por ir a la grabaci\u00f3n de un programa. Todav\u00eda son unos pocos los que lo hacen pero si acaba siendo una fuente extra para las cadenas (hay plat\u00f3s de 300 personas as\u00ed que un dinerillo pueden sacarse) espero que no se les ocurra llevarlo tambi\u00e9n a las audiencias en casa y cobrar por verlo desde el sof\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicidad No es la primera vez que hablo de publicidad extranjera aprovechando que he estado unos d\u00edas de vacaciones. Siempre me resulta curioso ver las similitudes y diferencias, tanto en conceptos como en marcas. As\u00ed que cuando vi uno que me pareci\u00f3 igualito al de Ikea pens\u00e9 que hab\u00edan adaptado el perfil m\u00e1s n\u00f3rdico a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,5,2,3],"tags":[237,135],"class_list":["post-5685","post","type-post","status-publish","format-standard","hentry","category-cine","category-internet","category-publicidad","category-television","tag-ikea","tag-salas-de-cine"],"_links":{"self":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/5685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/comments?post=5685"}],"version-history":[{"count":4,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/5685\/revisions"}],"predecessor-version":[{"id":5691,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/5685\/revisions\/5691"}],"wp:attachment":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/media?parent=5685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/categories?post=5685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/tags?post=5685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}