{"id":32134,"date":"2021-02-03T08:08:00","date_gmt":"2021-02-03T07:08:00","guid":{"rendered":"https:\/\/www.evasanagustin.com\/workaholic\/?p=32134"},"modified":"2026-01-05T14:26:24","modified_gmt":"2026-01-05T13:26:24","slug":"media-news-s05-a21","status":"publish","type":"post","link":"https:\/\/www.evasanagustin.com\/workaholic\/2021\/02\/03\/media-news-s05-a21\/","title":{"rendered":"Media News S05 A21"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Publicidad<\/strong><br \/>Comida y psicolog\u00eda van de la mano, es un hecho f\u00e1cilmente demostrable por cualquiera a la hora de cenar. Buitoni lo empieza a probar con <a href=\"https:\/\/www.youtube.com\/watch?v=NUAIdh-eRCA\">su serie \u00abTenemos que hablar\u00bb<\/a> donde las \u00bfmalas? noticias se toman de otra manera despu\u00e9s de comer su pizza. El anuncio en televisi\u00f3n invita sutilmente a ver m\u00e1s historias online y, de momento, hay una sobre madres (un poco lejos de su d\u00eda). Me imaginaba una sitcom y les ha quedado m\u00e1s bien un v\u00eddeo un poquito m\u00e1s largo, pero as\u00ed ha estrenado Buitoni su <a href=\"https:\/\/www.youtube.com\/channel\/UCdoGGwgafsQf9Kr3KOC5PKg\">canal en YouTube<\/a> (hasta ahora lo publicaban todo en Nestl\u00e9 Cocina). Por cierto, <a href=\"https:\/\/www.youtube.com\/watch?v=yHN5DbcGmMQ\">en el de Francia<\/a> vayan m\u00e1s avanzados en la serie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Televisi\u00f3n<\/strong><br \/>Sigo con la psicolog\u00eda, ahora combinada con la tele y las series porque <a href=\"https:\/\/www.vogue.es\/belleza\/articulos\/ver-una-serie-beneficios-emocionales-psicologos-netflix-amazon\">parece que reducen en estr\u00e9s<\/a>. As\u00ed que, despu\u00e9s de estresarte por el tiempo que se tarda en elegir qu\u00e9 poner, se ve, se libera dopamina y acabamos m\u00e1s felices que al empezar. Adem\u00e1s, sirve para ser m\u00e1s sociables, provocar cambios y hasta organiza mejor nuestra jornada. Tiene sentido desde un punto de vista de gui\u00f3n: nos controlan emocionalmente durante todo el cap\u00edtulo, algunas veces haciendo que nos enganchemos toda la temporada. \u00bfPor qu\u00e9? Porque queremos saber qu\u00e9 decisiones tomar\u00e1n los personajes. \u00bfEso nos hace m\u00e1s felices? Bueno, es m\u00e1s relajante que tomar las propias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cine<\/strong><br \/>Lo peor que le puede pasar a una pel\u00edcula es que no consigas entrar en ella. Ya sabes, es cuando acabas pensando en otra cosa, como qu\u00e9 har\u00e1s cuando termine o qu\u00e9 hubiera pasado si hubieses elegido ver una serie (recuerda el p\u00e1rrafo anterior: te puede hacer m\u00e1s feliz). Tambi\u00e9n es malo cuando te empanas intentando recordar d\u00f3nde has visto a ese actor, qui\u00e9n canta esa canci\u00f3n o en qu\u00e9 otra peli pasaba algo parecido. Dir\u00eda que esto \u00faltimo es lo peor porque puede ser dif\u00edcil de averiguar (lo otro Google o IMDb lo responden) y te puede fastidiar todo el visionado (iba a decir proyecci\u00f3n, pero, en fin, eso ya queda en el recuerdo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Internet<\/strong><br \/>Otra m\u00e1s. Otra red social m\u00e1s que busca nuestra atenci\u00f3n. Despu\u00e9s del boom por la imagen y del v\u00eddeo, era de esperar que le tocase al audio, m\u00e1s evidente a\u00fan despu\u00e9s de que <a href=\"https:\/\/twitter.com\/losdelvolcan\/status\/1354460728464437252\">el podcast subiese como la espuma<\/a>. Pero ya se sabe que una forma de ganar usuarios es con invitaci\u00f3n y que se genera m\u00e1s ruido cuando m\u00e1s exclusividad se respira, as\u00ed que <a href=\"https:\/\/andro4all.com\/noticias\/apps-android\/clubhouse-para-android-cuando-estara-disponible\">a\u00fan no est\u00e1 disponible<\/a> para todos los m\u00f3viles. No hay problema, no tengo ninguna prisa por probarla. No me apetece surfear esa ola porque, a\u00fan no me habr\u00e9 recuperado y ya vendr\u00e1 otra. Ser\u00e1 que soy de otra generaci\u00f3n (l\u00e9ase como una forma elegante de decir que me hago mayor), pero intento elegir mejor mis batallas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PublicidadComida y psicolog\u00eda van de la mano, es un hecho f\u00e1cilmente demostrable por cualquiera a la hora de cenar. Buitoni lo empieza a probar con su serie \u00abTenemos que hablar\u00bb donde las \u00bfmalas? noticias se toman de otra manera despu\u00e9s de comer su pizza. El anuncio en televisi\u00f3n invita sutilmente a ver m\u00e1s historias online [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,5,2,3],"tags":[310,490,181,68],"class_list":["post-32134","post","type-post","status-publish","format-standard","hentry","category-cine","category-internet","category-publicidad","category-television","tag-guion-de-cine","tag-marcas-de-alimentacion","tag-redes-sociales","tag-series-de-television"],"_links":{"self":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/32134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/comments?post=32134"}],"version-history":[{"count":3,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/32134\/revisions"}],"predecessor-version":[{"id":32142,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/32134\/revisions\/32142"}],"wp:attachment":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/media?parent=32134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/categories?post=32134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/tags?post=32134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}