{"id":126,"date":"2007-04-22T17:08:17","date_gmt":"2007-04-22T15:08:17","guid":{"rendered":"http:\/\/www.evasanagustin.com\/workaholic\/?p=126"},"modified":"2026-01-05T13:56:21","modified_gmt":"2026-01-05T12:56:21","slug":"ad-soy-una-caja-de-sorpresas","status":"publish","type":"post","link":"https:\/\/www.evasanagustin.com\/workaholic\/2007\/04\/22\/ad-soy-una-caja-de-sorpresas\/","title":{"rendered":"[AD] \u00bfSoy una caja de sorpresas?"},"content":{"rendered":"<p>Hoy ha sido una de las pocas veces que he dejado de prestar atenci\u00f3n al peque\u00f1o recuadro que dejan en TVE al interrumpir el Mundial de Motociclismo para fijarme en la publicidad. A\u00fan no hab\u00eda visto <a href=\"http:\/\/www.anuncios.com\/publica\/drvisapi.dll?MIval=ptele&#038;ID=72342\" target=\"_blank\">lo nuevo de Aquarius<\/a> y, como hace <a href=\"http:\/\/downloadingmassmedia.blogspot.com\/2006\/07\/media-news-s29-06.html\">\u00faltimamente<\/a>, llama la atenci\u00f3n <a target=\"_blank\">esta vez<\/a>\u00a0hablando de estudios de mercado.<\/p>\n<p>De nuevo la Sra. Rushmore se pone en la piel del consumidor y nos da\u00a0voz para intentar convencernos de que <strong>no importa que las marcas intenten conocernos<\/strong>. Con sus encuestas y estudios de mercado, podr\u00edan saber\u00a0qu\u00e9 p\u00e1ginas visitamos, los programas o series\u00a0que vemos, los libros que leemos o la m\u00fasica que escuchamos. Pero\u00a0da igual porque, a\u00fan as\u00ed, las empresas no saben nada de nosotros: <strong>somos cajas de sorpresas<\/strong>.<\/p>\n<p>Es esp\u00edtiru del <a href=\"http:\/\/www.anuncios.com\/publica\/drvisapi.dll\/IDe46b3654270d8a?MIval=videoswmv&#038;ano=2007&#038;parent_id=72342&#038;idvideo=72343\" target=\"_blank\">spot<\/a> es el mismo que el de hace un tiempo que planteaba el fin de la era del marketing y la llegada de la era Aquarius porque <strong>hacemos lo que nos da la gana<\/strong>. Pero ha pasado el tiempo y yo me siento igual de \u00bfmanipulada? por este tipo de anuncios que utiliza los mismos medios para\u00a0lo mismo que el resto (se entiende, vender) pero que intentan ponerse de nuestro lado dici\u00e9ndonos que no lo est\u00e1n.<\/p>\n<p>Si nos lo dice Coca Cola, \u00bfnos creeremos que somos cajas de sorpresas? \u00bfEres impredecible?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy ha sido una de las pocas veces que he dejado de prestar atenci\u00f3n al peque\u00f1o recuadro que dejan en TVE al interrumpir el Mundial de Motociclismo para fijarme en la publicidad. A\u00fan no hab\u00eda visto lo nuevo de Aquarius y, como hace \u00faltimamente, llama la atenci\u00f3n esta vez\u00a0hablando de estudios de mercado. De nuevo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[2],"tags":[176,235],"class_list":["post-126","post","type-post","status-publish","format-standard","hentry","category-publicidad","tag-coca-cola","tag-marcas-de-bebidas-no-alcoholicas"],"_links":{"self":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":1,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":35994,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/posts\/126\/revisions\/35994"}],"wp:attachment":[{"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.evasanagustin.com\/workaholic\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}